{"id":391590,"date":"2023-03-01T10:41:14","date_gmt":"2023-03-01T13:41:14","guid":{"rendered":"https:\/\/www.oitaperunense.com.br\/site\/?p=391590"},"modified":"2023-03-01T10:41:14","modified_gmt":"2023-03-01T13:41:14","slug":"saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna","status":"publish","type":"post","link":"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/","title":{"rendered":"Sa\u00fade: Aplicativo auxilia a combater o mosquito Aedes aegypti em Itaperuna"},"content":{"rendered":"<p class=\"yiv4865701504MsoNormal\" style=\"text-align: center;\"><strong>Com o aplicativo \u00e9 poss\u00edvel que todas as unidades de sa\u00fade do munic\u00edpio lancem informa\u00e7\u00f5es de atendimentos a pacientes, com suspeitas ou contaminados pelo Aedes aegypti<\/strong><\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">Em Itaperuna, RJ, a Secretaria Municipal de Sa\u00fade vem se destacando no interior do Estado do Rio de Janeiro, devido a uma s\u00e9rie de programas e projetos que beneficiam consideravelmente a popula\u00e7\u00e3o do munic\u00edpio. \u2018Consult\u00f3rio na Rua\u2019; \u2018Programa Equoterapia Pedra Preta\u2019; \u2018Equipe de Sa\u00fade Itinerante\u2019; descentraliza\u00e7\u00e3o de marca\u00e7\u00e3o de exames, permitindo \u00e0 popula\u00e7\u00e3o acessar esses servi\u00e7os atrav\u00e9s das UBS (Unidade B\u00e1sica de Sa\u00fade); \u2018Programa Aten\u00e7\u00e3o Integral \u00e0 Sa\u00fade da Pessoa Idosa\u2019 s\u00e3o exemplos bem-sucedidos de projetos realizados na cidade. Outro setor que vem se destacando \u00e9 a Coordena\u00e7\u00e3o de Vigil\u00e2ncia Ambiental em Sa\u00fade (CVAS), que dentre as suas prerrogativas, realiza a\u00e7\u00f5es estrat\u00e9gicas de combate ao mosquito&nbsp;<i>Aedes aegypti<\/i>. E, conta com uma importante ferramenta \u2013 um aplicativo, desenvolvido pelo programador e t\u00e9cnico em inform\u00e1tica Leonardo Carvalho \u2013 que consegue mapear as localidades com maior \u00edndice de notifica\u00e7\u00e3o de pessoas suspeitas de arboviroses.<\/p>\n<p><!--more--><\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">Com o aplicativo \u00e9 poss\u00edvel monitorar a presen\u00e7a das f\u00eameas do&nbsp;<i>Aedes aegypti<\/i>, transmissor dos v\u00edrus da dengue, chikungunya, zika, febre amarela entre outras doen\u00e7as. Atrav\u00e9s desse mapeamento, poss\u00edveis pontos onde foram detectados a presen\u00e7a do mosquito, \u00e9 poss\u00edvel ampliar as a\u00e7\u00f5es de bloqueios focal (dentro das casas), perifocal (quintal) e UBV (carro fumac\u00ea).<\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">A metodologia desenvolvida e implementada no aplicativo \u00e9 pioneira no Estado do Rio de Janeiro. Inclusive, durante cinco meses que ficou em fase experimental, mostrou-se totalmente eficaz, resolutivo e eficiente, ao localizar as pessoas que foram contaminadas por arboviroses, causadas por v\u00edrus transmitidos pelos mosquitos&nbsp;<i>Aedes Aegypti<\/i>&nbsp;e&nbsp;<i>Aedes Albopictus<\/i>, permitindo que a equipe realizasse a\u00e7\u00f5es para bloquear a prolifera\u00e7\u00e3o dessas doen\u00e7as.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-391592 aligncenter\" src=\"https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/03\/APLI2.jpg\" alt=\"\" width=\"700\" height=\"482\" srcset=\"https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/03\/APLI2.jpg 700w, https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/03\/APLI2-300x207.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><strong>Adriano Rodrigues de Azevedo, coordenador da CVAS, utiliza o aplicativo para planejar as a\u00e7\u00f5es das equipes<\/strong><\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">Com a ferramenta \u00e9 poss\u00edvel que as unidades de sa\u00fade do munic\u00edpio, sendo elas, Unidade B\u00e1sica de Sa\u00fade (UBS), Unidade de Pronto Atendimento (UPA), Posto de Urg\u00eancia (P.U.), UAP (Unidade Ambulatorial Pedi\u00e1trica Mariza Mozer) e hospitais lancem as informa\u00e7\u00f5es de atendimentos de pacientes com suspeitas ou contaminados pelos v\u00edrus transmitidos pelos mosquitos. Posteriormente, as informa\u00e7\u00f5es s\u00e3o inseridas no banco de dados que v\u00e3o cruzar com outras plataformas; e lan\u00e7adas em um mapa (tecnologia de sat\u00e9lite).<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-391593 aligncenter\" src=\"https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/03\/APLI3.jpg\" alt=\"\" width=\"700\" height=\"422\" srcset=\"https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/03\/APLI3.jpg 700w, https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/03\/APLI3-300x181.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><strong>O aplicativo foi desenvolvido pelo programador e t\u00e9cnico em inform\u00e1tica Leonardo Carvalho<\/strong><\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">Com esses dados, a equipe da CVAS entra em cena e envia seus agentes de combate \u00e0s endemias, para a localidade onde o paciente em quest\u00e3o reside, a fim de realizar a a\u00e7\u00e3o de supervis\u00e3o, investiga\u00e7\u00e3o, inspe\u00e7\u00e3o e an\u00e1lise da situa\u00e7\u00e3o; para ent\u00e3o determinar qual opera\u00e7\u00e3o ser\u00e1 necess\u00e1ria.<\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\"><b>CARRO FUMAC\u00ca<\/b><\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">Caso haja a necessidade do uso do carro fumac\u00ea, o aplicativo gera e mapeia o melhor trajeto para a a\u00e7\u00e3o, al\u00e9m de monitorar a localiza\u00e7\u00e3o do ve\u00edculo em tempo real e gravar todo o trajeto. Assim, consegue-se diminuir o consumo de combust\u00edvel, com o percurso exato da \u00e1rea de atua\u00e7\u00e3o, diminuindo o tempo de trabalho, economizando a quantidade de inseticida usado na a\u00e7\u00e3o, implicando diretamente na preserva\u00e7\u00e3o do ambiente e prote\u00e7\u00e3o dos animais.<\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">\u00c9 importante frisar que o carro fumac\u00ea \u00e9 usado em \u00faltimo caso, em situa\u00e7\u00f5es extremas, por conter alto teor qu\u00edmico. A aplica\u00e7\u00e3o de inseticida por UBV pesado, para a forma adulta ou alado do mosquito \u00e9 utilizado apenas nos casos da confirma\u00e7\u00e3o da doen\u00e7a ou do v\u00edrus no local das notifica\u00e7\u00f5es.<\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\"><b>MAPA GERADO POR GEOPROCESSAMENTO<\/b><\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">Ao utilizar o aplicativo, o mapa gerado pelo geoprocessamento indica dois raios de atua\u00e7\u00e3o, mostrando o per\u00edmetro onde dever\u00e1 ser feita a\u00e7\u00e3o de controle vetorial do&nbsp;<i>Aedes aegypti<\/i>, com raios de 150 e 300 metros.<\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">No raio de 150 metros, a equipe faz o trabalho utilizando controle mec\u00e2nico, procurando focos, colhendo larvas, eliminando dep\u00f3sitos que possam servir de reservat\u00f3rios para \u00e1gua parada, al\u00e9m de orientar os moradores com mensagens educativas e se necess\u00e1rio, realizar o trabalho com m\u00e1quinas costais para aplica\u00e7\u00e3o do inseticida.<\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">J\u00e1 no raio de 300 metros \u00e9 usado a UBV pesado (carro fumac\u00ea), depois de confirmada a circula\u00e7\u00e3o de f\u00eameas do mosquito, infectadas no local; positivado atrav\u00e9s de an\u00e1lise feita pelo laborat\u00f3rio de entomologia. Somente nestas circunst\u00e2ncias, \u00e9 que se cogita a necessidade do uso do carro fumac\u00ea.<\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">Em todo o ano de 2022, o munic\u00edpio de Itaperuna notificou 1.287 casos de pessoas com sintomas da dengue, com 324 confirmados e 838 descartados. Os outros 125 casos seguem em investiga\u00e7\u00e3o.<\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\">Acompanhe as not\u00edcias e informa\u00e7\u00f5es sobre a Secretaria Municipal de Sa\u00fade e demais secretarias, pelas redes sociais da Prefeitura de Itaperuna!<\/p>\n<p class=\"yiv4865701504MsoNormal\" style=\"text-align: justify;\"><b><i>Com informa\u00e7\u00f5es: DECOM\/Itaperuna\/RJ<\/i><\/b><i><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o aplicativo \u00e9 poss\u00edvel que todas as unidades de sa\u00fade do munic\u00edpio lancem informa\u00e7\u00f5es de atendimentos a pacientes, com suspeitas ou contaminados pelo Aedes aegypti Em Itaperuna, RJ, a Secretaria Municipal de Sa\u00fade vem se destacando no interior do Estado do Rio de Janeiro, devido a uma s\u00e9rie de programas e projetos que beneficiam [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":391591,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[113],"tags":[],"class_list":["post-391590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sa\u00fade: Aplicativo auxilia a combater o mosquito Aedes aegypti em Itaperuna - O Itaperunense<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sa\u00fade: Aplicativo auxilia a combater o mosquito Aedes aegypti em Itaperuna - O Itaperunense\" \/>\n<meta property=\"og:description\" content=\"Com o aplicativo \u00e9 poss\u00edvel que todas as unidades de sa\u00fade do munic\u00edpio lancem informa\u00e7\u00f5es de atendimentos a pacientes, com suspeitas ou contaminados pelo Aedes aegypti Em Itaperuna, RJ, a Secretaria Municipal de Sa\u00fade vem se destacando no interior do Estado do Rio de Janeiro, devido a uma s\u00e9rie de programas e projetos que beneficiam [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/\" \/>\n<meta property=\"og:site_name\" content=\"O Itaperunense\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaloitaperunense\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-01T13:41:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/03\/APLI.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"449\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andr\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andr\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/\",\"url\":\"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/\",\"name\":\"Sa\u00fade: Aplicativo auxilia a combater o mosquito Aedes aegypti em Itaperuna - O Itaperunense\",\"isPartOf\":{\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/#website\"},\"datePublished\":\"2023-03-01T13:41:14+00:00\",\"dateModified\":\"2023-03-01T13:41:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/4a5b86c112157bc0a4492f4fd6b7939f\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.oitaperunense.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sa\u00fade: Aplicativo auxilia a combater o mosquito Aedes aegypti em Itaperuna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/#website\",\"url\":\"https:\/\/www.oitaperunense.com.br\/site\/\",\"name\":\"O Itaperunense\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oitaperunense.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/4a5b86c112157bc0a4492f4fd6b7939f\",\"name\":\"Andr\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7a7a912ec2c8cd6a390040b03329ee7a71bbd5f81ac3557b6a68208f263fc97b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7a7a912ec2c8cd6a390040b03329ee7a71bbd5f81ac3557b6a68208f263fc97b?s=96&d=mm&r=g\",\"caption\":\"Andr\u00e9\"},\"url\":\"https:\/\/www.oitaperunense.com.br\/site\/author\/andre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sa\u00fade: Aplicativo auxilia a combater o mosquito Aedes aegypti em Itaperuna - O Itaperunense","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/","og_locale":"pt_BR","og_type":"article","og_title":"Sa\u00fade: Aplicativo auxilia a combater o mosquito Aedes aegypti em Itaperuna - O Itaperunense","og_description":"Com o aplicativo \u00e9 poss\u00edvel que todas as unidades de sa\u00fade do munic\u00edpio lancem informa\u00e7\u00f5es de atendimentos a pacientes, com suspeitas ou contaminados pelo Aedes aegypti Em Itaperuna, RJ, a Secretaria Municipal de Sa\u00fade vem se destacando no interior do Estado do Rio de Janeiro, devido a uma s\u00e9rie de programas e projetos que beneficiam [&hellip;]","og_url":"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/","og_site_name":"O Itaperunense","article_publisher":"https:\/\/www.facebook.com\/jornaloitaperunense","article_published_time":"2023-03-01T13:41:14+00:00","og_image":[{"width":700,"height":449,"url":"https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/03\/APLI.jpg","type":"image\/jpeg"}],"author":"Andr\u00e9","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andr\u00e9","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/","url":"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/","name":"Sa\u00fade: Aplicativo auxilia a combater o mosquito Aedes aegypti em Itaperuna - O Itaperunense","isPartOf":{"@id":"https:\/\/www.oitaperunense.com.br\/site\/#website"},"datePublished":"2023-03-01T13:41:14+00:00","dateModified":"2023-03-01T13:41:14+00:00","author":{"@id":"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/4a5b86c112157bc0a4492f4fd6b7939f"},"breadcrumb":{"@id":"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.oitaperunense.com.br\/site\/saude-aplicativo-auxilia-a-combater-o-mosquito-aedes-aegypti-em-itaperuna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oitaperunense.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Sa\u00fade: Aplicativo auxilia a combater o mosquito Aedes aegypti em Itaperuna"}]},{"@type":"WebSite","@id":"https:\/\/www.oitaperunense.com.br\/site\/#website","url":"https:\/\/www.oitaperunense.com.br\/site\/","name":"O Itaperunense","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oitaperunense.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/4a5b86c112157bc0a4492f4fd6b7939f","name":"Andr\u00e9","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7a7a912ec2c8cd6a390040b03329ee7a71bbd5f81ac3557b6a68208f263fc97b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7a7a912ec2c8cd6a390040b03329ee7a71bbd5f81ac3557b6a68208f263fc97b?s=96&d=mm&r=g","caption":"Andr\u00e9"},"url":"https:\/\/www.oitaperunense.com.br\/site\/author\/andre\/"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/posts\/391590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/comments?post=391590"}],"version-history":[{"count":1,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/posts\/391590\/revisions"}],"predecessor-version":[{"id":391594,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/posts\/391590\/revisions\/391594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/media\/391591"}],"wp:attachment":[{"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/media?parent=391590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/categories?post=391590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/tags?post=391590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}