{"id":391461,"date":"2023-02-07T15:45:01","date_gmt":"2023-02-07T18:45:01","guid":{"rendered":"https:\/\/www.oitaperunense.com.br\/site\/?p=391461"},"modified":"2023-02-08T07:49:17","modified_gmt":"2023-02-08T10:49:17","slug":"micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra","status":"publish","type":"post","link":"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/","title":{"rendered":"Micro-organismos dever\u00e3o potencializar efic\u00e1cia dos fertilizantes agr\u00edcolas da Terra"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Empresa pretende ampliar presen\u00e7a dos bioinsumos em seus produtos, aumentando seu poder de fertiliza\u00e7\u00e3o, num processo integrado de economia circular e sustentabilidade ambiental<\/strong><\/p>\n<p style=\"text-align: justify;\">Na esteira da expans\u00e3o do mercado de bioinsumos no Brasil, que cresce 40% ao ano, conforme mostra a pesquisa&nbsp;<i>Market Overview &#8211; Biological Products<\/i>, realizada pela Bip Spark, a Tera Ambiental, que produz fertilizantes org\u00e2nicos compostos da linha Tera Nutri\u00e7\u00e3o Vegetal a partir da compostagem do lodo de esgotos e efluentes industriais, contratou o bi\u00f3logo Maur\u00edcio Zagatto, mestre pela Universidade Federal do Paran\u00e1 e doutor em Ci\u00eancia do Solo pela ESALQ-USP. Objetivo \u00e9 realizar estudos destinados a potencializar a capacidade do produto de promover o crescimento dos vegetais. Para isso, o especialista realizar\u00e1 pesquisas visando ao aumento da presen\u00e7a de micro-organismos nos compostos.<br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\">A iniciativa da empresa est\u00e1 em linha com o desenvolvimento de produtos biol\u00f3gicos para uso na agricultura, cujo crescimento no Brasil d\u00e1-se num patamar bem mais elevado do que na m\u00e9dia global, segundo o Departamento de Sanidade Vegetal e Insumos Agr\u00edcolas do Minist\u00e9rio da Agricultura, Pecu\u00e1ria e Abastecimento. \u201cO fertilizante Tera j\u00e1 possui ampla abund\u00e2ncia e diversidade de microrganismos, tendo em vista a origem dos materiais que s\u00e3o compostados para sua produ\u00e7\u00e3o. Dessa forma, existe a possibilidade de isolar microrganismos promotores de crescimento vegetal do pr\u00f3prio fertilizante, multiplic\u00e1-los e reinocul\u00e1-los no pr\u00f3prio composto\u201d, observa Zagatto.<\/p>\n<p style=\"text-align: justify;\">Outra forma de enriquecer o produto \u00e9 por meio da multiplica\u00e7\u00e3o e inocula\u00e7\u00e3o de cepas comerciais. \u201cA propaga\u00e7\u00e3o de microrganismos promotores de crescimento inoculados no solo depender\u00e1 da capacidade competitiva das cepas inseridas, bem como dos teores de macro e micronutrientes, mat\u00e9ria org\u00e2nica e manejo adequado do solo\u201d, explica o especialista.<\/p>\n<p style=\"text-align: justify;\">Inicialmente, ser\u00e1 aumentada a densidade de microrganismos promotores de crescimento vegetal espec\u00edficos no fertilizante Tera, de modo a propiciar maior agrega\u00e7\u00e3o de valor e qualidade. Para o escalonamento do processo, ser\u00e1 necess\u00e1ria a produ\u00e7\u00e3o pr\u00f3pria de microrganismos promotores de crescimento vegetal, para se evitar gastos com a compra. \u201cA propaga\u00e7\u00e3o de pr\u00e1ticas de manejo sustent\u00e1veis, como rota\u00e7\u00e3o de culturas, plantio direto, combina\u00e7\u00e3o de fertilizantes org\u00e2nicos com minerais e utiliza\u00e7\u00e3o de plantas de cobertura, ser\u00e1 fundamental para que os microrganismos inoculados no fertilizante Tera possam propagar-se no solo agr\u00edcola\u201d, ressalta o bi\u00f3logo.<\/p>\n<p style=\"text-align: justify;\">Ser\u00e3o objeto da pesquisa os seguintes g\u00eaneros e esp\u00e9cies de micro-organismos:<strong>&nbsp;<\/strong><i>Trichoderma harzianum<\/i>;&nbsp;<i>Trichoderma asperellum<\/i>;&nbsp;<i>Azospirillum brasiliense<\/i>;&nbsp;<i>Bacillus subtilizo<\/i>;&nbsp;<i>Bacillus thurigiensis; Bacillus amyoliquefasciens; Bacillus pumillus; Bacillus velezensis;&nbsp;<\/i>e<i>&nbsp;Pseudomonas<\/i>.<\/p>\n<p style=\"text-align: justify;\"><strong>Solu\u00e7\u00f5es ambientais para <\/strong><strong>valorizar res\u00edduos org\u00e2nicos<\/strong><\/p>\n<p style=\"text-align: justify;\">A Tera Nutri\u00e7\u00e3o Vegetal \u00e9 respons\u00e1vel pela representa\u00e7\u00e3o e comercializa\u00e7\u00e3o dos fertilizantes org\u00e2nicos compostos Tera Base, Mix e Premium, produzidos por compostagem termof\u00edlica. Al\u00e9m de ambientalmente sustent\u00e1veis, pois t\u00eam origem na reciclagem de res\u00edduos org\u00e2nicos urbanos, industriais e agroindustriais, o grande potencial dos produtos est\u00e1 em seu conte\u00fado de mat\u00e9ria org\u00e2nica, subst\u00e2ncias h\u00famicas, microrganismos, macro e micronutrientes.<\/p>\n<p style=\"text-align: justify;\">Por isso, os fertilizantes proporcionam m\u00faltiplos benef\u00edcios ao sistema solo-planta, desde os aspectos nutricionais dos vegetais e melhorias nas propriedades f\u00edsicas, qu\u00edmicas e biol\u00f3gicas da terra, at\u00e9 sua capacidade de supress\u00e3o de fitopat\u00f3genos, promovendo de todas as formas ganhos de produtividade. Podem ser utilizados em qualquer cultura. Destacam-se o caf\u00e9, cana-de-a\u00e7\u00facar, gr\u00e3os, citros, frut\u00edferas tropicais e de clima temperado, florestas de eucalipto, hortali\u00e7as, tub\u00e9rculos, pastagens, parques, jardins, floreiras e plantas ornamentais.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-391463 aligncenter\" src=\"https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/02\/link.jpg\" alt=\"\" width=\"700\" height=\"467\" srcset=\"https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/02\/link.jpg 700w, https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/02\/link-300x200.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: justify;\">Os fertilizantes da Tera Nutri\u00e7\u00e3o Vegetal proporcionam os seguintes benef\u00edcios: fornecem grande diversidade de macro e micronutrientes \u00e0s plantas; ampliam a capacidade do solo em reter nutrientes, evitando perdas e gerando economia na manuten\u00e7\u00e3o na \u00e1rea aplicada; s\u00e3o \u00f3timos condicionador de solo com NPK, macro e micronutriente, contendo umidade com libera\u00e7\u00e3o lenta e cont\u00ednua; ricos em mat\u00e9ria org\u00e2nica e subst\u00e2ncias h\u00famicas, estimulando o crescimento mais r\u00e1pido das plantas e o surgimento de novas radicelas (performance radicular); t\u00eam alta capacidade de reten\u00e7\u00e3o de \u00e1gua no solo; promovem supress\u00e3o a microrganismos fitopatog\u00eanicos e controle de pragas tipo nematoides; e t\u00eam efeito residual, mantendo a fun\u00e7\u00e3o biol\u00f3gica prolongada da aplica\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Como resultados, os produtos proporcionam aumento da produtividade e redu\u00e7\u00e3o de aduba\u00e7\u00e3o. S\u00e3o indicados para solos pouco produtivos ou pobres em mat\u00e9ria org\u00e2nica e quando h\u00e1 necessidade de cria\u00e7\u00e3o de novas radicelas, reten\u00e7\u00e3o de nutrientes e de \u00e1gua e potencializa\u00e7\u00e3o do uso dos fertilizantes minerais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empresa pretende ampliar presen\u00e7a dos bioinsumos em seus produtos, aumentando seu poder de fertiliza\u00e7\u00e3o, num processo integrado de economia circular e sustentabilidade ambiental Na esteira da expans\u00e3o do mercado de bioinsumos no Brasil, que cresce 40% ao ano, conforme mostra a pesquisa&nbsp;Market Overview &#8211; Biological Products, realizada pela Bip Spark, a Tera Ambiental, que produz [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":391462,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-391461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Micro-organismos dever\u00e3o potencializar efic\u00e1cia dos fertilizantes agr\u00edcolas da Terra - O Itaperunense<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Micro-organismos dever\u00e3o potencializar efic\u00e1cia dos fertilizantes agr\u00edcolas da Terra - O Itaperunense\" \/>\n<meta property=\"og:description\" content=\"Empresa pretende ampliar presen\u00e7a dos bioinsumos em seus produtos, aumentando seu poder de fertiliza\u00e7\u00e3o, num processo integrado de economia circular e sustentabilidade ambiental Na esteira da expans\u00e3o do mercado de bioinsumos no Brasil, que cresce 40% ao ano, conforme mostra a pesquisa&nbsp;Market Overview &#8211; Biological Products, realizada pela Bip Spark, a Tera Ambiental, que produz [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/\" \/>\n<meta property=\"og:site_name\" content=\"O Itaperunense\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jornaloitaperunense\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-07T18:45:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:49:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/02\/link-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andr\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andr\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/\",\"url\":\"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/\",\"name\":\"Micro-organismos dever\u00e3o potencializar efic\u00e1cia dos fertilizantes agr\u00edcolas da Terra - O Itaperunense\",\"isPartOf\":{\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/#website\"},\"datePublished\":\"2023-02-07T18:45:01+00:00\",\"dateModified\":\"2023-02-08T10:49:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/4a5b86c112157bc0a4492f4fd6b7939f\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.oitaperunense.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Micro-organismos dever\u00e3o potencializar efic\u00e1cia dos fertilizantes agr\u00edcolas da Terra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/#website\",\"url\":\"https:\/\/www.oitaperunense.com.br\/site\/\",\"name\":\"O Itaperunense\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oitaperunense.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/4a5b86c112157bc0a4492f4fd6b7939f\",\"name\":\"Andr\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7a7a912ec2c8cd6a390040b03329ee7a71bbd5f81ac3557b6a68208f263fc97b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7a7a912ec2c8cd6a390040b03329ee7a71bbd5f81ac3557b6a68208f263fc97b?s=96&d=mm&r=g\",\"caption\":\"Andr\u00e9\"},\"url\":\"https:\/\/www.oitaperunense.com.br\/site\/author\/andre\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Micro-organismos dever\u00e3o potencializar efic\u00e1cia dos fertilizantes agr\u00edcolas da Terra - O Itaperunense","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/","og_locale":"pt_BR","og_type":"article","og_title":"Micro-organismos dever\u00e3o potencializar efic\u00e1cia dos fertilizantes agr\u00edcolas da Terra - O Itaperunense","og_description":"Empresa pretende ampliar presen\u00e7a dos bioinsumos em seus produtos, aumentando seu poder de fertiliza\u00e7\u00e3o, num processo integrado de economia circular e sustentabilidade ambiental Na esteira da expans\u00e3o do mercado de bioinsumos no Brasil, que cresce 40% ao ano, conforme mostra a pesquisa&nbsp;Market Overview &#8211; Biological Products, realizada pela Bip Spark, a Tera Ambiental, que produz [&hellip;]","og_url":"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/","og_site_name":"O Itaperunense","article_publisher":"https:\/\/www.facebook.com\/jornaloitaperunense","article_published_time":"2023-02-07T18:45:01+00:00","article_modified_time":"2023-02-08T10:49:17+00:00","og_image":[{"width":700,"height":467,"url":"https:\/\/www.oitaperunense.com.br\/site\/wp-content\/uploads\/2023\/02\/link-1.jpg","type":"image\/jpeg"}],"author":"Andr\u00e9","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andr\u00e9","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/","url":"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/","name":"Micro-organismos dever\u00e3o potencializar efic\u00e1cia dos fertilizantes agr\u00edcolas da Terra - O Itaperunense","isPartOf":{"@id":"https:\/\/www.oitaperunense.com.br\/site\/#website"},"datePublished":"2023-02-07T18:45:01+00:00","dateModified":"2023-02-08T10:49:17+00:00","author":{"@id":"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/4a5b86c112157bc0a4492f4fd6b7939f"},"breadcrumb":{"@id":"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.oitaperunense.com.br\/site\/micro-organismos-deverao-potencializar-eficacia-dos-fertilizantes-agricolas-da-terra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oitaperunense.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Micro-organismos dever\u00e3o potencializar efic\u00e1cia dos fertilizantes agr\u00edcolas da Terra"}]},{"@type":"WebSite","@id":"https:\/\/www.oitaperunense.com.br\/site\/#website","url":"https:\/\/www.oitaperunense.com.br\/site\/","name":"O Itaperunense","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oitaperunense.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/4a5b86c112157bc0a4492f4fd6b7939f","name":"Andr\u00e9","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.oitaperunense.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7a7a912ec2c8cd6a390040b03329ee7a71bbd5f81ac3557b6a68208f263fc97b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7a7a912ec2c8cd6a390040b03329ee7a71bbd5f81ac3557b6a68208f263fc97b?s=96&d=mm&r=g","caption":"Andr\u00e9"},"url":"https:\/\/www.oitaperunense.com.br\/site\/author\/andre\/"}]}},"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/posts\/391461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/comments?post=391461"}],"version-history":[{"count":3,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/posts\/391461\/revisions"}],"predecessor-version":[{"id":391467,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/posts\/391461\/revisions\/391467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/media\/391462"}],"wp:attachment":[{"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/media?parent=391461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/categories?post=391461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oitaperunense.com.br\/site\/wp-json\/wp\/v2\/tags?post=391461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}